{"id":172699,"date":"2015-03-23T12:18:21","date_gmt":"2015-03-23T10:18:21","guid":{"rendered":"http:\/\/beta.paokfc.gr\/paok-tv\/europa-league\/"},"modified":"2015-03-23T12:18:21","modified_gmt":"2015-03-23T10:18:21","slug":"europa-league","status":"publish","type":"page","link":"https:\/\/dv4.paokfc.gr\/en\/paok-tv\/europa-league\/","title":{"rendered":"Europa League"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":1130,"menu_order":10,"comment_status":"open","ping_status":"open","template":"video-gallery.php","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-172699","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Europa League - PAOKFC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dv4.paokfc.gr\/en\/paok-tv\/europa-league\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Europa League - PAOKFC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dv4.paokfc.gr\/en\/paok-tv\/europa-league\/\" \/>\n<meta property=\"og:site_name\" content=\"PAOKFC\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dv4.paokfc.gr\/en\/paok-tv\/europa-league\/\",\"url\":\"https:\/\/dv4.paokfc.gr\/en\/paok-tv\/europa-league\/\",\"name\":\"Europa League - PAOKFC\",\"isPartOf\":{\"@id\":\"https:\/\/dv4.paokfc.gr\/#website\"},\"datePublished\":\"2015-03-23T10:18:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dv4.paokfc.gr\/en\/paok-tv\/europa-league\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dv4.paokfc.gr\/en\/paok-tv\/europa-league\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dv4.paokfc.gr\/en\/paok-tv\/europa-league\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dv4.paokfc.gr\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PAOK TV\",\"item\":\"https:\/\/dv4.paokfc.gr\/en\/paok-tv\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Europa League\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dv4.paokfc.gr\/#website\",\"url\":\"https:\/\/dv4.paokfc.gr\/\",\"name\":\"PAOKFC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dv4.paokfc.gr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dv4.paokfc.gr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dv4.paokfc.gr\/#organization\",\"name\":\"PAOK FC\",\"url\":\"https:\/\/dv4.paokfc.gr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dv4.paokfc.gr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dv4.paokfc.gr\/wp-content\/uploads\/2014\/07\/PAOKfc_main_logo.jpg\",\"contentUrl\":\"https:\/\/dv4.paokfc.gr\/wp-content\/uploads\/2014\/07\/PAOKfc_main_logo.jpg\",\"width\":760,\"height\":510,\"caption\":\"PAOK FC\"},\"image\":{\"@id\":\"https:\/\/dv4.paokfc.gr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Europa League - PAOKFC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dv4.paokfc.gr\/en\/paok-tv\/europa-league\/","og_locale":"en_US","og_type":"article","og_title":"Europa League - PAOKFC","og_url":"https:\/\/dv4.paokfc.gr\/en\/paok-tv\/europa-league\/","og_site_name":"PAOKFC","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dv4.paokfc.gr\/en\/paok-tv\/europa-league\/","url":"https:\/\/dv4.paokfc.gr\/en\/paok-tv\/europa-league\/","name":"Europa League - PAOKFC","isPartOf":{"@id":"https:\/\/dv4.paokfc.gr\/#website"},"datePublished":"2015-03-23T10:18:21+00:00","breadcrumb":{"@id":"https:\/\/dv4.paokfc.gr\/en\/paok-tv\/europa-league\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dv4.paokfc.gr\/en\/paok-tv\/europa-league\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dv4.paokfc.gr\/en\/paok-tv\/europa-league\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dv4.paokfc.gr\/en\/"},{"@type":"ListItem","position":2,"name":"PAOK TV","item":"https:\/\/dv4.paokfc.gr\/en\/paok-tv\/"},{"@type":"ListItem","position":3,"name":"Europa League"}]},{"@type":"WebSite","@id":"https:\/\/dv4.paokfc.gr\/#website","url":"https:\/\/dv4.paokfc.gr\/","name":"PAOKFC","description":"","publisher":{"@id":"https:\/\/dv4.paokfc.gr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dv4.paokfc.gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dv4.paokfc.gr\/#organization","name":"PAOK FC","url":"https:\/\/dv4.paokfc.gr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dv4.paokfc.gr\/#\/schema\/logo\/image\/","url":"https:\/\/dv4.paokfc.gr\/wp-content\/uploads\/2014\/07\/PAOKfc_main_logo.jpg","contentUrl":"https:\/\/dv4.paokfc.gr\/wp-content\/uploads\/2014\/07\/PAOKfc_main_logo.jpg","width":760,"height":510,"caption":"PAOK FC"},"image":{"@id":"https:\/\/dv4.paokfc.gr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dv4.paokfc.gr\/en\/wp-json\/wp\/v2\/pages\/172699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dv4.paokfc.gr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dv4.paokfc.gr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dv4.paokfc.gr\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dv4.paokfc.gr\/en\/wp-json\/wp\/v2\/comments?post=172699"}],"version-history":[{"count":0,"href":"https:\/\/dv4.paokfc.gr\/en\/wp-json\/wp\/v2\/pages\/172699\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/dv4.paokfc.gr\/en\/wp-json\/wp\/v2\/pages\/1130"}],"wp:attachment":[{"href":"https:\/\/dv4.paokfc.gr\/en\/wp-json\/wp\/v2\/media?parent=172699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}